{"id":10260,"date":"2024-04-24T11:57:08","date_gmt":"2024-04-24T09:57:08","guid":{"rendered":"https:\/\/soplair.com\/productos\/accesorios-para-toldos\/paquete-de-10-ventosas\/"},"modified":"2024-07-02T14:43:39","modified_gmt":"2024-07-02T12:43:39","slug":"paquete-de-10-ventosas","status":"publish","type":"page","link":"https:\/\/soplair.com\/es\/productos\/accesorios-para-avances\/paquete-de-10-ventosas\/","title":{"rendered":"Paquete de 10 ventosas"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"10260\" class=\"elementor elementor-10260 elementor-4129\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-17a0a95b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"17a0a95b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-40ee6076\" data-id=\"40ee6076\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d87bafe elementor-widget elementor-widget-jet-breadcrumbs\" data-id=\"3d87bafe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-jet-breadcrumbs jet-blocks\">\n\t\t<div class=\"jet-breadcrumbs\">\n\t\t<div class=\"jet-breadcrumbs__content\">\n\t\t<div class=\"jet-breadcrumbs__wrap\"><div class=\"jet-breadcrumbs__item\"><a href=\"https:\/\/soplair.com\/es\/\" class=\"jet-breadcrumbs__item-link is-home\" rel=\"home\" title=\"Inicio\">Inicio<\/a><\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3dade6a5 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"3dade6a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;autoplay_speed&quot;:3500,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrusel de im\u00e1genes\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 2\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/soplair.com\/wp-content\/uploads\/2024\/04\/tampons-fixation-1-218x300.png\" alt=\"tampons fixation\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 2\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/soplair.com\/wp-content\/uploads\/2024\/04\/tampons-fixation-2-221x300.png\" alt=\"tampons fixation 2\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d9f4d54 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4d9f4d54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d70cad6 elementor-widget elementor-widget-heading\" data-id=\"5d70cad6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">PAQUETE DE 10 VENTOSAS<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-695df855 elementor-widget elementor-widget-text-editor\" data-id=\"695df855\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5><strong>Precio de venta recomendado: desde 14,90\u20ac<\/strong><\/h5>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58f5f4a0 elementor-widget elementor-widget-text-editor\" data-id=\"58f5f4a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><strong>Ref. : 855602<\/strong><\/h4>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2984a2e6 elementor-widget elementor-widget-text-editor\" data-id=\"2984a2e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5>Accesorios indispensables para avances hinchables parciales para caravanas y avances hinchables para autocaravanas y furgonetas. Las ventosas presionan la lona del avance contra la pared de su veh\u00edculo, evitando corrientes de aire y filtraciones de agua en el interior del avance, <strong><a href=\"#ancre\">ver m\u00e1s &#8230;<\/a><\/strong><\/h5>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6fd61d0d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6fd61d0d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4c0085be\" data-id=\"4c0085be\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fc8cced elementor-widget elementor-widget-menu-anchor\" data-id=\"fc8cced\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"ancla\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24b231bb elementor-widget elementor-widget-jet-accordion\" data-id=\"24b231bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"jet-accordion\" data-settings=\"{&quot;collapsible&quot;:false,&quot;ajaxTemplate&quot;:false,&quot;switchScrolling&quot;:false,&quot;switchScrollingOffset&quot;:0,&quot;switchScrollingDelay&quot;:500}\">\n\t\t\t<div class=\"jet-accordion__inner\">\n\t\t\t\t<div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-6151\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"1\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-6151\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-left\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><i class=\"fas fa-plus\"><\/i><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><i class=\"fas fa-minus\"><\/i><\/span><\/div><div class=\"jet-toggle__label-text\">Descripci\u00f3n<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-6151\" class=\"jet-toggle__content\" data-toggle=\"1\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><p>Accesorios indispensables para avances hinchables parciales para caravanas y avances hinchables para autocaravanas y furgonetas.<br \/>Las ventosas presionan la lona del avance contra la pared de su veh\u00edculo, evitando corrientes de aire y filtraciones de agua en el interior del avance.<br \/>Vers\u00e1tiles, tambi\u00e9n pueden utilizarse para colgar todo tipo de objetos.<br \/>F\u00edjalo a la pared enroscando la tapa en la ventosa.<\/p>\n<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-6152\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"2\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-6152\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-left\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><i class=\"fas fa-plus\"><\/i><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><i class=\"fas fa-minus\"><\/i><\/span><\/div><div class=\"jet-toggle__label-text\">Para m\u00e1s informaci\u00f3n<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-6152\" class=\"jet-toggle__content\" data-toggle=\"2\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><p>PVC transparente de gran adherencia. Paquete de 10 unidades.<\/p>\n<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-6153\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"3\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-6153\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-left\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><i class=\"fas fa-plus\"><\/i><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><i class=\"fas fa-minus\"><\/i><\/span><\/div><div class=\"jet-toggle__label-text\">Accesorios adicionales<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-6153\" class=\"jet-toggle__content\" data-toggle=\"3\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\">Tab Item Content<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Accueil PAQUETE DE 10 VENTOSAS Precio de venta recomendado: desde 14,90\u20ac Ref. : 855602 Accesorios indispensables para avances hinchables parciales para caravanas y avances hinchables para autocaravanas y furgonetas. Las ventosas presionan la lona del avance contra la pared de su veh\u00edculo, evitando corrientes de aire y filtraciones de agua en el interior del avance, [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":10238,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-10260","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Paquete de 10 ventosas - Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/soplair.com\/es\/productos\/accesorios-para-avances\/paquete-de-10-ventosas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paquete de 10 ventosas - Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...\" \/>\n<meta property=\"og:description\" content=\"Accueil PAQUETE DE 10 VENTOSAS Precio de venta recomendado: desde 14,90\u20ac Ref. : 855602 Accesorios indispensables para avances hinchables parciales para caravanas y avances hinchables para autocaravanas y furgonetas. Las ventosas presionan la lona del avance contra la pared de su veh\u00edculo, evitando corrientes de aire y filtraciones de agua en el interior del avance, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/soplair.com\/es\/productos\/accesorios-para-avances\/paquete-de-10-ventosas\/\" \/>\n<meta property=\"og:site_name\" content=\"Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-02T12:43:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/soplair.com\/wp-content\/uploads\/2024\/04\/tampons-fixation-1-218x300.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/soplair.com\/es\/productos\/accesorios-para-avances\/paquete-de-10-ventosas\/\",\"url\":\"https:\/\/soplair.com\/es\/productos\/accesorios-para-avances\/paquete-de-10-ventosas\/\",\"name\":\"Paquete de 10 ventosas - Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...\",\"isPartOf\":{\"@id\":\"https:\/\/soplair.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/soplair.com\/es\/productos\/accesorios-para-avances\/paquete-de-10-ventosas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/soplair.com\/es\/productos\/accesorios-para-avances\/paquete-de-10-ventosas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/soplair.com\/wp-content\/uploads\/2024\/04\/tampons-fixation-1-218x300.png\",\"datePublished\":\"2024-04-24T09:57:08+00:00\",\"dateModified\":\"2024-07-02T12:43:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/soplair.com\/es\/productos\/accesorios-para-avances\/paquete-de-10-ventosas\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/soplair.com\/es\/productos\/accesorios-para-avances\/paquete-de-10-ventosas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/soplair.com\/es\/productos\/accesorios-para-avances\/paquete-de-10-ventosas\/#primaryimage\",\"url\":\"https:\/\/soplair.com\/wp-content\/uploads\/2024\/04\/tampons-fixation-1-218x300.png\",\"contentUrl\":\"https:\/\/soplair.com\/wp-content\/uploads\/2024\/04\/tampons-fixation-1-218x300.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/soplair.com\/es\/productos\/accesorios-para-avances\/paquete-de-10-ventosas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Productos\",\"item\":\"https:\/\/soplair.com\/es\/productos\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Accesorios para avances\",\"item\":\"https:\/\/soplair.com\/es\/produits\/accessoires-auvents\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Paquete de 10 ventosas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/soplair.com\/es\/#website\",\"url\":\"https:\/\/soplair.com\/es\/\",\"name\":\"Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...\",\"description\":\"ISOLANTS THERMIQUES &amp; MOBILIERS DE PLEIN-AIR POUR VOS LOISIRS. Les produits SOPLAIR. AUVENTS TRADITIONNELS &amp; GONFLABLES SP\u00c9CIAL CARAVANES.\",\"publisher\":{\"@id\":\"https:\/\/soplair.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/soplair.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/soplair.com\/es\/#organization\",\"name\":\"Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...\",\"url\":\"https:\/\/soplair.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/soplair.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/soplair.com\/wp-content\/uploads\/2020\/01\/cropped-Fichier-1.png\",\"contentUrl\":\"https:\/\/soplair.com\/wp-content\/uploads\/2020\/01\/cropped-Fichier-1.png\",\"width\":1719,\"height\":507,\"caption\":\"Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...\"},\"image\":{\"@id\":\"https:\/\/soplair.com\/es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paquete de 10 ventosas - Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/soplair.com\/es\/productos\/accesorios-para-avances\/paquete-de-10-ventosas\/","og_locale":"es_ES","og_type":"article","og_title":"Paquete de 10 ventosas - Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...","og_description":"Accueil PAQUETE DE 10 VENTOSAS Precio de venta recomendado: desde 14,90\u20ac Ref. : 855602 Accesorios indispensables para avances hinchables parciales para caravanas y avances hinchables para autocaravanas y furgonetas. Las ventosas presionan la lona del avance contra la pared de su veh\u00edculo, evitando corrientes de aire y filtraciones de agua en el interior del avance, [&hellip;]","og_url":"https:\/\/soplair.com\/es\/productos\/accesorios-para-avances\/paquete-de-10-ventosas\/","og_site_name":"Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...","article_modified_time":"2024-07-02T12:43:39+00:00","og_image":[{"url":"https:\/\/soplair.com\/wp-content\/uploads\/2024\/04\/tampons-fixation-1-218x300.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/soplair.com\/es\/productos\/accesorios-para-avances\/paquete-de-10-ventosas\/","url":"https:\/\/soplair.com\/es\/productos\/accesorios-para-avances\/paquete-de-10-ventosas\/","name":"Paquete de 10 ventosas - Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...","isPartOf":{"@id":"https:\/\/soplair.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/soplair.com\/es\/productos\/accesorios-para-avances\/paquete-de-10-ventosas\/#primaryimage"},"image":{"@id":"https:\/\/soplair.com\/es\/productos\/accesorios-para-avances\/paquete-de-10-ventosas\/#primaryimage"},"thumbnailUrl":"https:\/\/soplair.com\/wp-content\/uploads\/2024\/04\/tampons-fixation-1-218x300.png","datePublished":"2024-04-24T09:57:08+00:00","dateModified":"2024-07-02T12:43:39+00:00","breadcrumb":{"@id":"https:\/\/soplair.com\/es\/productos\/accesorios-para-avances\/paquete-de-10-ventosas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/soplair.com\/es\/productos\/accesorios-para-avances\/paquete-de-10-ventosas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/soplair.com\/es\/productos\/accesorios-para-avances\/paquete-de-10-ventosas\/#primaryimage","url":"https:\/\/soplair.com\/wp-content\/uploads\/2024\/04\/tampons-fixation-1-218x300.png","contentUrl":"https:\/\/soplair.com\/wp-content\/uploads\/2024\/04\/tampons-fixation-1-218x300.png"},{"@type":"BreadcrumbList","@id":"https:\/\/soplair.com\/es\/productos\/accesorios-para-avances\/paquete-de-10-ventosas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Productos","item":"https:\/\/soplair.com\/es\/productos\/"},{"@type":"ListItem","position":2,"name":"Accesorios para avances","item":"https:\/\/soplair.com\/es\/produits\/accessoires-auvents\/"},{"@type":"ListItem","position":3,"name":"Paquete de 10 ventosas"}]},{"@type":"WebSite","@id":"https:\/\/soplair.com\/es\/#website","url":"https:\/\/soplair.com\/es\/","name":"Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...","description":"ISOLANTS THERMIQUES &amp; MOBILIERS DE PLEIN-AIR POUR VOS LOISIRS. Les produits SOPLAIR. AUVENTS TRADITIONNELS &amp; GONFLABLES SP\u00c9CIAL CARAVANES.","publisher":{"@id":"https:\/\/soplair.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/soplair.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/soplair.com\/es\/#organization","name":"Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...","url":"https:\/\/soplair.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/soplair.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/soplair.com\/wp-content\/uploads\/2020\/01\/cropped-Fichier-1.png","contentUrl":"https:\/\/soplair.com\/wp-content\/uploads\/2020\/01\/cropped-Fichier-1.png","width":1719,"height":507,"caption":"Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ..."},"image":{"@id":"https:\/\/soplair.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/soplair.com\/es\/wp-json\/wp\/v2\/pages\/10260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soplair.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/soplair.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/soplair.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/soplair.com\/es\/wp-json\/wp\/v2\/comments?post=10260"}],"version-history":[{"count":3,"href":"https:\/\/soplair.com\/es\/wp-json\/wp\/v2\/pages\/10260\/revisions"}],"predecessor-version":[{"id":13163,"href":"https:\/\/soplair.com\/es\/wp-json\/wp\/v2\/pages\/10260\/revisions\/13163"}],"up":[{"embeddable":true,"href":"https:\/\/soplair.com\/es\/wp-json\/wp\/v2\/pages\/10238"}],"wp:attachment":[{"href":"https:\/\/soplair.com\/es\/wp-json\/wp\/v2\/media?parent=10260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}