{"id":10354,"date":"2024-04-22T15:26:03","date_gmt":"2024-04-22T13:26:03","guid":{"rendered":"https:\/\/soplair.com\/productos\/toldos-tradicionales-e-hinchables\/proyeccion-de-fachada-para-toldo-de-caravana\/"},"modified":"2024-07-08T16:24:51","modified_gmt":"2024-07-08T14:24:51","slug":"proyeccion-de-fachada-para-avance-de-caravana","status":"publish","type":"page","link":"https:\/\/soplair.com\/es\/productos\/avances-tradicionales-e-hinchables\/proyeccion-de-fachada-para-avance-de-caravana\/","title":{"rendered":"Proyecci\u00f3n de fachada para avance de caravana"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"10354\" class=\"elementor elementor-10354 elementor-3719\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-17a0a95b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"17a0a95b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-40ee6076\" data-id=\"40ee6076\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d87bafe elementor-widget elementor-widget-jet-breadcrumbs\" data-id=\"3d87bafe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-jet-breadcrumbs jet-blocks\">\n\t\t<div class=\"jet-breadcrumbs\">\n\t\t<div class=\"jet-breadcrumbs__content\">\n\t\t<div class=\"jet-breadcrumbs__wrap\"><div class=\"jet-breadcrumbs__item\"><a href=\"https:\/\/soplair.com\/es\/\" class=\"jet-breadcrumbs__item-link is-home\" rel=\"home\" title=\"Inicio\">Inicio<\/a><\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3dade6a5 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"3dade6a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;autoplay_speed&quot;:3500,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrusel de im\u00e1genes\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 1\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/soplair.com\/wp-content\/uploads\/elementor\/thumbs\/avancee-auvent-rk41mn67prtexjb12pnaqe99k32qytuvr47e9fhk8c.png\" alt=\"avanc\u00e9e auvent\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d9f4d54 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4d9f4d54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d70cad6 elementor-widget elementor-widget-heading\" data-id=\"5d70cad6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">PROYECCI\u00d3N DE FACHADA PARA AVANCE DE CARAVANA<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-695df855 elementor-widget elementor-widget-text-editor\" data-id=\"695df855\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5><strong>Precio de venta recomendado: desde 322,00\u20ac<\/strong><\/h5>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58f5f4a0 elementor-widget elementor-widget-text-editor\" data-id=\"58f5f4a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><strong>Ref. :  <\/strong><b>P001375<\/b><\/h4>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2984a2e6 elementor-widget elementor-widget-text-editor\" data-id=\"2984a2e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5>Disfrute de una zona de sombra fuera de su avance. Este voladizo es compatible con todos los avances Soplair tradicionales y se fija a una varilla instalada de serie en la caperuza de su avance. Para m\u00e1s intimidad o para resguardarse del viento, puede completarse con paredes laterales, <strong><a href=\"#ancla\">ver m\u00e1s &#8230;<\/a><\/strong><\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-205c876 elementor-widget elementor-widget-heading\" data-id=\"205c876\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">PUNTOS CLAVE<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c7896a1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"c7896a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2a782c84 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2a782c84\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-169a1173\" data-id=\"169a1173\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ca2fae4\" data-id=\"ca2fae4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7aa68e6 elementor-widget elementor-widget-image\" data-id=\"7aa68e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"102\" height=\"99\" src=\"https:\/\/soplair.com\/wp-content\/uploads\/2024\/07\/19.png\" class=\"attachment-large size-large wp-image-15310\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e8df05 elementor-widget elementor-widget-text-editor\" data-id=\"9e8df05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong>19 tallas disponibles<\/strong><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2aad5b0c\" data-id=\"2aad5b0c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-77a68c24 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"77a68c24\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-56d797a1\" data-id=\"56d797a1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7fedc579 elementor-widget elementor-widget-menu-anchor\" data-id=\"7fedc579\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"ancla\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6fd61d0d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6fd61d0d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4c0085be\" data-id=\"4c0085be\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-24b231bb elementor-widget elementor-widget-jet-accordion\" data-id=\"24b231bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"jet-accordion\" data-settings=\"{&quot;collapsible&quot;:false,&quot;ajaxTemplate&quot;:false,&quot;switchScrolling&quot;:false,&quot;switchScrollingOffset&quot;:0,&quot;switchScrollingDelay&quot;:500}\">\n\t\t\t<div class=\"jet-accordion__inner\">\n\t\t\t\t<div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-6151\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"1\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-6151\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-left\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><i class=\"fas fa-plus\"><\/i><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><i class=\"fas fa-minus\"><\/i><\/span><\/div><div class=\"jet-toggle__label-text\">Descripci\u00f3n<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-6151\" class=\"jet-toggle__content\" data-toggle=\"1\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><p>Disfrute de una zona de sombra fuera de su avance. Este voladizo es compatible con todos los avances Soplair tradicionales y se fija a una varilla instalada de serie en la caperuza de su avance. Para m\u00e1s intimidad o para resguardarse del viento, puede completarse con paredes laterales.<\/p>\n<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-6152\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"2\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-6152\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-left\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><i class=\"fas fa-plus\"><\/i><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><i class=\"fas fa-minus\"><\/i><\/span><\/div><div class=\"jet-toggle__label-text\">Para m\u00e1s informaci\u00f3n<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-6152\" class=\"jet-toggle__content\" data-toggle=\"2\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><p>Se fija al avance mediante un anillo de sujeci\u00f3n instalado de serie en la tapa del avance.<\/p>\n<p> <span style=\"text-decoration: underline;\"><strong> Profundidad de la proyecci\u00f3n<\/strong><\/span> : 240 cm<\/p>\n<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-6153\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"3\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-6153\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-left\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><i class=\"fas fa-plus\"><\/i><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><i class=\"fas fa-minus\"><\/i><\/span><\/div><div class=\"jet-toggle__label-text\">Accesorios adicionales<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-6153\" class=\"jet-toggle__content\" data-toggle=\"3\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\">Tab Item Content<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Accueil PROYECCI\u00d3N DE FACHADA PARA AVANCE DE CARAVANA Precio de venta recomendado: desde 322,00\u20ac Ref. : P001375 Disfrute de una zona de sombra fuera de su avance. Este voladizo es compatible con todos los avances Soplair tradicionales y se fija a una varilla instalada de serie en la caperuza de su avance. Para m\u00e1s intimidad [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":10280,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-10354","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Proyecci\u00f3n de fachada para avance de caravana - Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/soplair.com\/es\/productos\/avances-tradicionales-e-hinchables\/proyeccion-de-fachada-para-avance-de-caravana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Proyecci\u00f3n de fachada para avance de caravana - Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...\" \/>\n<meta property=\"og:description\" content=\"Accueil PROYECCI\u00d3N DE FACHADA PARA AVANCE DE CARAVANA Precio de venta recomendado: desde 322,00\u20ac Ref. : P001375 Disfrute de una zona de sombra fuera de su avance. Este voladizo es compatible con todos los avances Soplair tradicionales y se fija a una varilla instalada de serie en la caperuza de su avance. Para m\u00e1s intimidad [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/soplair.com\/es\/productos\/avances-tradicionales-e-hinchables\/proyeccion-de-fachada-para-avance-de-caravana\/\" \/>\n<meta property=\"og:site_name\" content=\"Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-08T14:24:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/soplair.com\/wp-content\/uploads\/elementor\/thumbs\/avancee-auvent-qn35iaiwbytg1vleajyrk098fnlpsxdy5n7hx1ghws.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/soplair.com\/es\/productos\/avances-tradicionales-e-hinchables\/proyeccion-de-fachada-para-avance-de-caravana\/\",\"url\":\"https:\/\/soplair.com\/es\/productos\/avances-tradicionales-e-hinchables\/proyeccion-de-fachada-para-avance-de-caravana\/\",\"name\":\"Proyecci\u00f3n de fachada para avance de caravana - Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...\",\"isPartOf\":{\"@id\":\"https:\/\/soplair.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/soplair.com\/es\/productos\/avances-tradicionales-e-hinchables\/proyeccion-de-fachada-para-avance-de-caravana\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/soplair.com\/es\/productos\/avances-tradicionales-e-hinchables\/proyeccion-de-fachada-para-avance-de-caravana\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/soplair.com\/wp-content\/uploads\/elementor\/thumbs\/avancee-auvent-qn35iaiwbytg1vleajyrk098fnlpsxdy5n7hx1ghws.png\",\"datePublished\":\"2024-04-22T13:26:03+00:00\",\"dateModified\":\"2024-07-08T14:24:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/soplair.com\/es\/productos\/avances-tradicionales-e-hinchables\/proyeccion-de-fachada-para-avance-de-caravana\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/soplair.com\/es\/productos\/avances-tradicionales-e-hinchables\/proyeccion-de-fachada-para-avance-de-caravana\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/soplair.com\/es\/productos\/avances-tradicionales-e-hinchables\/proyeccion-de-fachada-para-avance-de-caravana\/#primaryimage\",\"url\":\"https:\/\/soplair.com\/wp-content\/uploads\/elementor\/thumbs\/avancee-auvent-qn35iaiwbytg1vleajyrk098fnlpsxdy5n7hx1ghws.png\",\"contentUrl\":\"https:\/\/soplair.com\/wp-content\/uploads\/elementor\/thumbs\/avancee-auvent-qn35iaiwbytg1vleajyrk098fnlpsxdy5n7hx1ghws.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/soplair.com\/es\/productos\/avances-tradicionales-e-hinchables\/proyeccion-de-fachada-para-avance-de-caravana\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Productos\",\"item\":\"https:\/\/soplair.com\/es\/productos\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avances tradicionales e hinchables\",\"item\":\"https:\/\/soplair.com\/es\/produits\/auvents-traditionnels-and-gonflables\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Proyecci\u00f3n de fachada para avance de caravana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/soplair.com\/es\/#website\",\"url\":\"https:\/\/soplair.com\/es\/\",\"name\":\"Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...\",\"description\":\"ISOLANTS THERMIQUES &amp; MOBILIERS DE PLEIN-AIR POUR VOS LOISIRS. Les produits SOPLAIR. AUVENTS TRADITIONNELS &amp; GONFLABLES SP\u00c9CIAL CARAVANES.\",\"publisher\":{\"@id\":\"https:\/\/soplair.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/soplair.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/soplair.com\/es\/#organization\",\"name\":\"Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...\",\"url\":\"https:\/\/soplair.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/soplair.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/soplair.com\/wp-content\/uploads\/2020\/01\/cropped-Fichier-1.png\",\"contentUrl\":\"https:\/\/soplair.com\/wp-content\/uploads\/2020\/01\/cropped-Fichier-1.png\",\"width\":1719,\"height\":507,\"caption\":\"Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...\"},\"image\":{\"@id\":\"https:\/\/soplair.com\/es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Proyecci\u00f3n de fachada para avance de caravana - Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/soplair.com\/es\/productos\/avances-tradicionales-e-hinchables\/proyeccion-de-fachada-para-avance-de-caravana\/","og_locale":"es_ES","og_type":"article","og_title":"Proyecci\u00f3n de fachada para avance de caravana - Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...","og_description":"Accueil PROYECCI\u00d3N DE FACHADA PARA AVANCE DE CARAVANA Precio de venta recomendado: desde 322,00\u20ac Ref. : P001375 Disfrute de una zona de sombra fuera de su avance. Este voladizo es compatible con todos los avances Soplair tradicionales y se fija a una varilla instalada de serie en la caperuza de su avance. Para m\u00e1s intimidad [&hellip;]","og_url":"https:\/\/soplair.com\/es\/productos\/avances-tradicionales-e-hinchables\/proyeccion-de-fachada-para-avance-de-caravana\/","og_site_name":"Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...","article_modified_time":"2024-07-08T14:24:51+00:00","og_image":[{"url":"https:\/\/soplair.com\/wp-content\/uploads\/elementor\/thumbs\/avancee-auvent-qn35iaiwbytg1vleajyrk098fnlpsxdy5n7hx1ghws.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/soplair.com\/es\/productos\/avances-tradicionales-e-hinchables\/proyeccion-de-fachada-para-avance-de-caravana\/","url":"https:\/\/soplair.com\/es\/productos\/avances-tradicionales-e-hinchables\/proyeccion-de-fachada-para-avance-de-caravana\/","name":"Proyecci\u00f3n de fachada para avance de caravana - Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...","isPartOf":{"@id":"https:\/\/soplair.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/soplair.com\/es\/productos\/avances-tradicionales-e-hinchables\/proyeccion-de-fachada-para-avance-de-caravana\/#primaryimage"},"image":{"@id":"https:\/\/soplair.com\/es\/productos\/avances-tradicionales-e-hinchables\/proyeccion-de-fachada-para-avance-de-caravana\/#primaryimage"},"thumbnailUrl":"https:\/\/soplair.com\/wp-content\/uploads\/elementor\/thumbs\/avancee-auvent-qn35iaiwbytg1vleajyrk098fnlpsxdy5n7hx1ghws.png","datePublished":"2024-04-22T13:26:03+00:00","dateModified":"2024-07-08T14:24:51+00:00","breadcrumb":{"@id":"https:\/\/soplair.com\/es\/productos\/avances-tradicionales-e-hinchables\/proyeccion-de-fachada-para-avance-de-caravana\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/soplair.com\/es\/productos\/avances-tradicionales-e-hinchables\/proyeccion-de-fachada-para-avance-de-caravana\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/soplair.com\/es\/productos\/avances-tradicionales-e-hinchables\/proyeccion-de-fachada-para-avance-de-caravana\/#primaryimage","url":"https:\/\/soplair.com\/wp-content\/uploads\/elementor\/thumbs\/avancee-auvent-qn35iaiwbytg1vleajyrk098fnlpsxdy5n7hx1ghws.png","contentUrl":"https:\/\/soplair.com\/wp-content\/uploads\/elementor\/thumbs\/avancee-auvent-qn35iaiwbytg1vleajyrk098fnlpsxdy5n7hx1ghws.png"},{"@type":"BreadcrumbList","@id":"https:\/\/soplair.com\/es\/productos\/avances-tradicionales-e-hinchables\/proyeccion-de-fachada-para-avance-de-caravana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Productos","item":"https:\/\/soplair.com\/es\/productos\/"},{"@type":"ListItem","position":2,"name":"Avances tradicionales e hinchables","item":"https:\/\/soplair.com\/es\/produits\/auvents-traditionnels-and-gonflables\/"},{"@type":"ListItem","position":3,"name":"Proyecci\u00f3n de fachada para avance de caravana"}]},{"@type":"WebSite","@id":"https:\/\/soplair.com\/es\/#website","url":"https:\/\/soplair.com\/es\/","name":"Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...","description":"ISOLANTS THERMIQUES &amp; MOBILIERS DE PLEIN-AIR POUR VOS LOISIRS. Les produits SOPLAIR. AUVENTS TRADITIONNELS &amp; GONFLABLES SP\u00c9CIAL CARAVANES.","publisher":{"@id":"https:\/\/soplair.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/soplair.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/soplair.com\/es\/#organization","name":"Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...","url":"https:\/\/soplair.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/soplair.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/soplair.com\/wp-content\/uploads\/2020\/01\/cropped-Fichier-1.png","contentUrl":"https:\/\/soplair.com\/wp-content\/uploads\/2020\/01\/cropped-Fichier-1.png","width":1719,"height":507,"caption":"Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ..."},"image":{"@id":"https:\/\/soplair.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/soplair.com\/es\/wp-json\/wp\/v2\/pages\/10354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soplair.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/soplair.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/soplair.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/soplair.com\/es\/wp-json\/wp\/v2\/comments?post=10354"}],"version-history":[{"count":14,"href":"https:\/\/soplair.com\/es\/wp-json\/wp\/v2\/pages\/10354\/revisions"}],"predecessor-version":[{"id":17283,"href":"https:\/\/soplair.com\/es\/wp-json\/wp\/v2\/pages\/10354\/revisions\/17283"}],"up":[{"embeddable":true,"href":"https:\/\/soplair.com\/es\/wp-json\/wp\/v2\/pages\/10280"}],"wp:attachment":[{"href":"https:\/\/soplair.com\/es\/wp-json\/wp\/v2\/media?parent=10354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}