{"id":10458,"date":"2024-05-02T11:02:08","date_gmt":"2024-05-02T09:02:08","guid":{"rendered":"https:\/\/soplair.com\/productos\/sillones\/sillon-belice\/"},"modified":"2024-07-08T14:40:17","modified_gmt":"2024-07-08T12:40:17","slug":"sillon-belice","status":"publish","type":"page","link":"https:\/\/soplair.com\/es\/productos\/sillones\/sillon-belice\/","title":{"rendered":"Sill\u00f3n Belice"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"10458\" class=\"elementor elementor-10458 elementor-6331\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6d6b98f7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6d6b98f7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1b6b5b4f\" data-id=\"1b6b5b4f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c2f57b9 elementor-widget elementor-widget-jet-breadcrumbs\" data-id=\"6c2f57b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-jet-breadcrumbs jet-blocks\">\n\t\t<div class=\"jet-breadcrumbs\">\n\t\t<div class=\"jet-breadcrumbs__content\">\n\t\t<div class=\"jet-breadcrumbs__wrap\"><div class=\"jet-breadcrumbs__item\"><a href=\"https:\/\/soplair.com\/es\/\" class=\"jet-breadcrumbs__item-link is-home\" rel=\"home\" title=\"Inicio\">Inicio<\/a><\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d871989 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"4d871989\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;autoplay_speed&quot;:3500,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrusel de im\u00e1genes\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/soplair.com\/wp-content\/uploads\/2024\/05\/belize-298x300.png\" alt=\"belize\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/soplair.com\/wp-content\/uploads\/2024\/05\/belize-2-300x300.png\" alt=\"belize 2\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/soplair.com\/wp-content\/uploads\/2024\/05\/belize-3-300x300.png\" alt=\"belize 3\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/soplair.com\/wp-content\/uploads\/2024\/05\/belize-4-300x300.png\" alt=\"belize 4\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-402eccdc elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"402eccdc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f2a59e1 elementor-widget elementor-widget-heading\" data-id=\"7f2a59e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">SILL\u00d3N BELIZE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f33ac95 elementor-widget elementor-widget-text-editor\" data-id=\"7f33ac95\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5><strong>Precio de venta recomendado : 59,90\u20ac<\/strong><\/h5>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6bd440cb elementor-widget elementor-widget-text-editor\" data-id=\"6bd440cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><strong>Ref. : 697192<\/strong><\/h4>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7513e8f elementor-widget elementor-widget-text-editor\" data-id=\"7513e8f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5>SOPLAIR ha revisitado su modelo de furgoneta especial para viajeros con necesidad de espacio, ofreciendo la BELIZE en una versi\u00f3n m\u00e1s robusta y elegante con reposabrazos de bamb\u00fa, <strong><a href=\"#ancla\">ver m\u00e1s &#8230;<\/a><\/strong><\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1fc5d1b9 elementor-widget elementor-widget-heading\" data-id=\"1fc5d1b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">PUNTOS CLAVE<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a27002 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"2a27002\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9315771 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9315771\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-57e6ae2\" data-id=\"57e6ae2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f029ab2 elementor-widget elementor-widget-image\" data-id=\"f029ab2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/soplair.com\/wp-content\/uploads\/elementor\/thumbs\/deperlant-rk418jl78chh1d5qm4p6axleno229e2rh96g1jd70s.png\" title=\"d\u00e9perlant\" alt=\"d\u00e9perlant\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a6263b elementor-widget elementor-widget-text-editor\" data-id=\"7a6263b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong>DEPERLANT<\/strong><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-922d824\" data-id=\"922d824\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a705656 elementor-widget elementor-widget-image\" data-id=\"a705656\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/soplair.com\/wp-content\/uploads\/elementor\/thumbs\/pliage-facile-rk418jl78chh1d5qm4p6axleno229e2rh96g1jd70s.png\" title=\"pliage facile\" alt=\"pliage facile\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c99555f elementor-widget elementor-widget-text-editor\" data-id=\"c99555f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><b>PLEGADO F\u00c1CIL<\/b><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-07a53cd\" data-id=\"07a53cd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eeb1b64 elementor-widget elementor-widget-image\" data-id=\"eeb1b64\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/soplair.com\/wp-content\/uploads\/elementor\/thumbs\/resistance-aux-uv-rk416tjupa4jr3nuodvsqd8zg8ju5d8h8q4ed9x6fg.png\" title=\"r\u00e9sistance aux uv\" alt=\"r\u00e9sistance aux uv\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68e5830 elementor-widget elementor-widget-text-editor\" data-id=\"68e5830\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><b>RESISTENCIA A LOS RAYOS UV<\/b><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-649807d\" data-id=\"649807d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-345cd45 elementor-widget elementor-widget-image\" data-id=\"345cd45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/soplair.com\/wp-content\/uploads\/elementor\/thumbs\/legerete-1-rk416m156lu967yrwams6f5ap5kwfsemjowij28bt8.png\" title=\"l\u00e9g\u00e8ret\u00e9\" alt=\"l\u00e9g\u00e8ret\u00e9\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-879e2da elementor-widget elementor-widget-text-editor\" data-id=\"879e2da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><b>Ligereza<\/b><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-723e3de8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"723e3de8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5d65ab19\" data-id=\"5d65ab19\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6cd08f95 elementor-widget elementor-widget-menu-anchor\" data-id=\"6cd08f95\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"ancla\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6147e44a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6147e44a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1000d717\" data-id=\"1000d717\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-785fe82 elementor-widget elementor-widget-jet-accordion\" data-id=\"785fe82\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"jet-accordion\" data-settings=\"{&quot;collapsible&quot;:false,&quot;ajaxTemplate&quot;:false,&quot;switchScrolling&quot;:false,&quot;switchScrollingOffset&quot;:0,&quot;switchScrollingDelay&quot;:500}\">\n\t\t\t<div class=\"jet-accordion__inner\">\n\t\t\t\t<div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-1261\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"1\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-1261\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-left\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><i class=\"fas fa-plus\"><\/i><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><i class=\"fas fa-minus\"><\/i><\/span><\/div><div class=\"jet-toggle__label-text\">Descripci\u00f3n<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-1261\" class=\"jet-toggle__content\" data-toggle=\"1\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><p><strong>SOPLAIR<\/strong> revisa su modelo de <strong>furgoneta <\/strong> especial para viajeros que necesitan espacio y ofrece la BELIZE en una versi\u00f3n m\u00e1s robusta y elegante, \u00a1con reposabrazos de bamb\u00fa!<\/p>\n<p>Ultraligera y compacta, pesa s\u00f3lo <strong> 2,7 kg<\/strong> plegada y mide s\u00f3lo <strong>66 x 57 x 8,5 cm (largo x ancho x grosor).<\/strong><\/p>\n<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-1262\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"2\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-1262\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-left\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><i class=\"fas fa-plus\"><\/i><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><i class=\"fas fa-minus\"><\/i><\/span><\/div><div class=\"jet-toggle__label-text\">Para m\u00e1s informaci\u00f3n<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-1262\" class=\"jet-toggle__content\" data-toggle=\"2\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><p>Tejido de malla 3D.<\/p>\n<p>Marco de aluminio. Reposabrazos de bamb\u00fa.<\/p>\n<p>Dimensiones abiertas (Largo x Fondo x Alto): 56 x 50 x 89 cm<\/p>\n<p>Dimensiones del asiento (Largo x Fondo x Alto): 46 x 42 x 42 cm<\/p>\n<p>Dimensiones plegado (Largo x Fondo x Alto): 66 x 57 x 8,5 cm<\/p>\n<p>Peso: 2,7 kg<\/p>\n<p>Carga m\u00e1xima : 100 kg<\/p>\n<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-1263\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"3\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-1263\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-left\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><i class=\"fas fa-plus\"><\/i><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><i class=\"fas fa-minus\"><\/i><\/span><\/div><div class=\"jet-toggle__label-text\">Accesorios adicionales<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-1263\" class=\"jet-toggle__content\" data-toggle=\"3\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Accueil SILL\u00d3N BELIZE Precio de venta recomendado : 59,90\u20ac Ref. : 697192 SOPLAIR ha revisitado su modelo de furgoneta especial para viajeros con necesidad de espacio, ofreciendo la BELIZE en una versi\u00f3n m\u00e1s robusta y elegante con reposabrazos de bamb\u00fa, ver m\u00e1s &#8230; PUNTOS CLAVE DEPERLANT PLEGADO F\u00c1CIL RESISTENCIA A LOS RAYOS UV Ligereza Descripci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":10440,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-10458","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sill\u00f3n Belice - Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/soplair.com\/es\/productos\/sillones\/sillon-belice\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sill\u00f3n Belice - Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...\" \/>\n<meta property=\"og:description\" content=\"Accueil SILL\u00d3N BELIZE Precio de venta recomendado : 59,90\u20ac Ref. : 697192 SOPLAIR ha revisitado su modelo de furgoneta especial para viajeros con necesidad de espacio, ofreciendo la BELIZE en una versi\u00f3n m\u00e1s robusta y elegante con reposabrazos de bamb\u00fa, ver m\u00e1s &#8230; PUNTOS CLAVE DEPERLANT PLEGADO F\u00c1CIL RESISTENCIA A LOS RAYOS UV Ligereza Descripci\u00f3n [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/soplair.com\/es\/productos\/sillones\/sillon-belice\/\" \/>\n<meta property=\"og:site_name\" content=\"Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-08T12:40:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/soplair.com\/wp-content\/uploads\/2024\/05\/belize-298x300.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/soplair.com\/es\/productos\/sillones\/sillon-belice\/\",\"url\":\"https:\/\/soplair.com\/es\/productos\/sillones\/sillon-belice\/\",\"name\":\"Sill\u00f3n Belice - Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...\",\"isPartOf\":{\"@id\":\"https:\/\/soplair.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/soplair.com\/es\/productos\/sillones\/sillon-belice\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/soplair.com\/es\/productos\/sillones\/sillon-belice\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/soplair.com\/wp-content\/uploads\/2024\/05\/belize-298x300.png\",\"datePublished\":\"2024-05-02T09:02:08+00:00\",\"dateModified\":\"2024-07-08T12:40:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/soplair.com\/es\/productos\/sillones\/sillon-belice\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/soplair.com\/es\/productos\/sillones\/sillon-belice\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/soplair.com\/es\/productos\/sillones\/sillon-belice\/#primaryimage\",\"url\":\"https:\/\/soplair.com\/wp-content\/uploads\/2024\/05\/belize-298x300.png\",\"contentUrl\":\"https:\/\/soplair.com\/wp-content\/uploads\/2024\/05\/belize-298x300.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/soplair.com\/es\/productos\/sillones\/sillon-belice\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Productos\",\"item\":\"https:\/\/soplair.com\/es\/productos\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sillones\",\"item\":\"https:\/\/soplair.com\/es\/productos\/sillones\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sill\u00f3n Belice\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/soplair.com\/es\/#website\",\"url\":\"https:\/\/soplair.com\/es\/\",\"name\":\"Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...\",\"description\":\"ISOLANTS THERMIQUES &amp; MOBILIERS DE PLEIN-AIR POUR VOS LOISIRS. Les produits SOPLAIR. AUVENTS TRADITIONNELS &amp; GONFLABLES SP\u00c9CIAL CARAVANES.\",\"publisher\":{\"@id\":\"https:\/\/soplair.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/soplair.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/soplair.com\/es\/#organization\",\"name\":\"Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...\",\"url\":\"https:\/\/soplair.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/soplair.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/soplair.com\/wp-content\/uploads\/2020\/01\/cropped-Fichier-1.png\",\"contentUrl\":\"https:\/\/soplair.com\/wp-content\/uploads\/2020\/01\/cropped-Fichier-1.png\",\"width\":1719,\"height\":507,\"caption\":\"Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...\"},\"image\":{\"@id\":\"https:\/\/soplair.com\/es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sill\u00f3n Belice - Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/soplair.com\/es\/productos\/sillones\/sillon-belice\/","og_locale":"es_ES","og_type":"article","og_title":"Sill\u00f3n Belice - Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...","og_description":"Accueil SILL\u00d3N BELIZE Precio de venta recomendado : 59,90\u20ac Ref. : 697192 SOPLAIR ha revisitado su modelo de furgoneta especial para viajeros con necesidad de espacio, ofreciendo la BELIZE en una versi\u00f3n m\u00e1s robusta y elegante con reposabrazos de bamb\u00fa, ver m\u00e1s &#8230; PUNTOS CLAVE DEPERLANT PLEGADO F\u00c1CIL RESISTENCIA A LOS RAYOS UV Ligereza Descripci\u00f3n [&hellip;]","og_url":"https:\/\/soplair.com\/es\/productos\/sillones\/sillon-belice\/","og_site_name":"Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...","article_modified_time":"2024-07-08T12:40:17+00:00","og_image":[{"url":"https:\/\/soplair.com\/wp-content\/uploads\/2024\/05\/belize-298x300.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/soplair.com\/es\/productos\/sillones\/sillon-belice\/","url":"https:\/\/soplair.com\/es\/productos\/sillones\/sillon-belice\/","name":"Sill\u00f3n Belice - Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...","isPartOf":{"@id":"https:\/\/soplair.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/soplair.com\/es\/productos\/sillones\/sillon-belice\/#primaryimage"},"image":{"@id":"https:\/\/soplair.com\/es\/productos\/sillones\/sillon-belice\/#primaryimage"},"thumbnailUrl":"https:\/\/soplair.com\/wp-content\/uploads\/2024\/05\/belize-298x300.png","datePublished":"2024-05-02T09:02:08+00:00","dateModified":"2024-07-08T12:40:17+00:00","breadcrumb":{"@id":"https:\/\/soplair.com\/es\/productos\/sillones\/sillon-belice\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/soplair.com\/es\/productos\/sillones\/sillon-belice\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/soplair.com\/es\/productos\/sillones\/sillon-belice\/#primaryimage","url":"https:\/\/soplair.com\/wp-content\/uploads\/2024\/05\/belize-298x300.png","contentUrl":"https:\/\/soplair.com\/wp-content\/uploads\/2024\/05\/belize-298x300.png"},{"@type":"BreadcrumbList","@id":"https:\/\/soplair.com\/es\/productos\/sillones\/sillon-belice\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Productos","item":"https:\/\/soplair.com\/es\/productos\/"},{"@type":"ListItem","position":2,"name":"Sillones","item":"https:\/\/soplair.com\/es\/productos\/sillones\/"},{"@type":"ListItem","position":3,"name":"Sill\u00f3n Belice"}]},{"@type":"WebSite","@id":"https:\/\/soplair.com\/es\/#website","url":"https:\/\/soplair.com\/es\/","name":"Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...","description":"ISOLANTS THERMIQUES &amp; MOBILIERS DE PLEIN-AIR POUR VOS LOISIRS. Les produits SOPLAIR. AUVENTS TRADITIONNELS &amp; GONFLABLES SP\u00c9CIAL CARAVANES.","publisher":{"@id":"https:\/\/soplair.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/soplair.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/soplair.com\/es\/#organization","name":"Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...","url":"https:\/\/soplair.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/soplair.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/soplair.com\/wp-content\/uploads\/2020\/01\/cropped-Fichier-1.png","contentUrl":"https:\/\/soplair.com\/wp-content\/uploads\/2020\/01\/cropped-Fichier-1.png","width":1719,"height":507,"caption":"Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ..."},"image":{"@id":"https:\/\/soplair.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/soplair.com\/es\/wp-json\/wp\/v2\/pages\/10458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soplair.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/soplair.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/soplair.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/soplair.com\/es\/wp-json\/wp\/v2\/comments?post=10458"}],"version-history":[{"count":9,"href":"https:\/\/soplair.com\/es\/wp-json\/wp\/v2\/pages\/10458\/revisions"}],"predecessor-version":[{"id":17131,"href":"https:\/\/soplair.com\/es\/wp-json\/wp\/v2\/pages\/10458\/revisions\/17131"}],"up":[{"embeddable":true,"href":"https:\/\/soplair.com\/es\/wp-json\/wp\/v2\/pages\/10440"}],"wp:attachment":[{"href":"https:\/\/soplair.com\/es\/wp-json\/wp\/v2\/media?parent=10458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}