{"id":12740,"date":"2024-04-29T16:24:44","date_gmt":"2024-04-29T14:24:44","guid":{"rendered":"https:\/\/soplair.com\/productos\/mesas\/mesa-agora-2p\/"},"modified":"2024-07-08T10:59:40","modified_gmt":"2024-07-08T08:59:40","slug":"mesa-agora-2p","status":"publish","type":"page","link":"https:\/\/soplair.com\/es\/productos\/mesas\/mesa-agora-2p\/","title":{"rendered":"Mesa Agora 2P"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"12740\" class=\"elementor elementor-12740 elementor-5652\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3ca514c1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3ca514c1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-52aa99e\" data-id=\"52aa99e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1343b981 elementor-widget elementor-widget-jet-breadcrumbs\" data-id=\"1343b981\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-jet-breadcrumbs jet-blocks\">\n\t\t<div class=\"jet-breadcrumbs\">\n\t\t<div class=\"jet-breadcrumbs__content\">\n\t\t<div class=\"jet-breadcrumbs__wrap\"><div class=\"jet-breadcrumbs__item\"><a href=\"https:\/\/soplair.com\/es\/\" class=\"jet-breadcrumbs__item-link is-home\" rel=\"home\" title=\"Inicio\">Inicio<\/a><\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b945a73 elementor-widget__width-auto elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"b945a73\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;autoplay_speed&quot;:3500,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrusel de im\u00e1genes\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/soplair.com\/wp-content\/uploads\/2024\/07\/agora-2-1-1.png\" alt=\"agora-2-1.png\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/soplair.com\/wp-content\/uploads\/elementor\/thumbs\/agora-2-2-1-rk41pbzdykur8whpwcdlvdrmtt8zog40qkudy9sfsw.png\" alt=\"agora-2-2.png\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/soplair.com\/wp-content\/uploads\/elementor\/thumbs\/agora-2-3-rk41rccyktlu2vkl5pnvpdi4khc9553coj2rwkt4hs.png\" alt=\"agora-2.png\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/soplair.com\/wp-content\/uploads\/elementor\/thumbs\/agora-6-rk41q9tksm52uv4ker06d5887om7djucv8bv88e9kw.png\" alt=\"agora-6.png\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/soplair.com\/wp-content\/uploads\/elementor\/thumbs\/agora-5-1-rk41suvll7ogs9debd88pzqv0tvjjl3s80wxqmkagw.png\" alt=\"agora-5.png\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/soplair.com\/wp-content\/uploads\/elementor\/thumbs\/agora-4-1-rk41pcx85ew1kigcqus8fvj3f74cw57r2phvfjr1mo.png\" alt=\"agora-4.png\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ea914f6 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"2ea914f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63b7fe9b elementor-widget elementor-widget-heading\" data-id=\"63b7fe9b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">MESA AGORA 2 PERSONAS<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-288dd40 elementor-widget elementor-widget-text-editor\" data-id=\"288dd40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5><strong>Precio de venta recomendado : 149,90\u20ac<\/strong><\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-16169d9f elementor-widget elementor-widget-text-editor\" data-id=\"16169d9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><strong>Ref. : 697123<\/strong><\/h4>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6dfe804c elementor-widget elementor-widget-text-editor\" data-id=\"6dfe804c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5>Esta es la mesa SOPLAIR AGORA. Una mesa digna de su sal\u00f3n, pero adecuada para acampar, <strong><a href=\"#ancla\">ver m\u00e1s &#8230; <\/a><\/strong><\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-598684e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"598684e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-30c41f4\" data-id=\"30c41f4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c6cdaa8 elementor-widget elementor-widget-heading\" data-id=\"c6cdaa8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">PUNTOS CLAVE<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cd09a5e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"cd09a5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d3173ee elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d3173ee\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-1fff93b\" data-id=\"1fff93b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17dec63 elementor-widget elementor-widget-image\" data-id=\"17dec63\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/soplair.com\/wp-content\/uploads\/elementor\/thumbs\/Resistant-rk417zul8tqg9jyete60ckkq6krcrqweejh8yq6gng.png\" title=\"R\u00e9sistant\" alt=\"R\u00e9sistant\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f8ef0c elementor-widget elementor-widget-text-editor\" data-id=\"6f8ef0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><b>RESISTENTE<\/b><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-b863658\" data-id=\"b863658\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6cf0cc1 elementor-widget elementor-widget-image\" data-id=\"6cf0cc1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/soplair.com\/wp-content\/uploads\/elementor\/thumbs\/Entretien-facile-1-rk417jvc0n4ks6lmep9co6lw30y44w4yocdzt0u5l8.png\" title=\"Entretien facile\" alt=\"Entretien facile\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a13d51 elementor-widget elementor-widget-text-editor\" data-id=\"5a13d51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><b>F\u00c1CIL MANTENIMIENTO<\/b><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-bf7b3f1\" data-id=\"bf7b3f1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b17f1b elementor-widget elementor-widget-image\" data-id=\"3b17f1b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/soplair.com\/wp-content\/uploads\/elementor\/thumbs\/pliage-facile-rk418jl78chh1d5qm4p6axleno229e2rh96g1jd70s.png\" title=\"pliage facile\" alt=\"pliage facile\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-10cec32 elementor-widget elementor-widget-text-editor\" data-id=\"10cec32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><b>PLEGADO F\u00c1CIL<\/b><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-a70f98b\" data-id=\"a70f98b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8bb1c5d elementor-widget elementor-widget-image\" data-id=\"8bb1c5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/soplair.com\/wp-content\/uploads\/elementor\/thumbs\/pliage-ultra-rapide-rk416qqc4s0os9ry4unx0vylo2xqi9xa8c5xxg1cy4.png\" title=\"pliage ultra rapide\" alt=\"pliage ultra rapide\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9344ab7 elementor-widget elementor-widget-text-editor\" data-id=\"9344ab7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><b>PLEGADO ULTRARR\u00c1PIDO<\/b><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-690669f1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"690669f1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-487d5044\" data-id=\"487d5044\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5dd55ebd elementor-align-center e-transform elementor-widget elementor-widget-jet-download-button\" data-id=\"5dd55ebd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.1,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"jet-download-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-jet-download-button jet-elements\"><a class=\"elementor-button elementor-size-md jet-download jet-download-icon-position-left\" data-e-disable-page-transition=\"true\" href=\"https:\/\/soplair.com\/es\/?jet_download=a54a4f7a8445537da0e67b5ba78335ebfd81d0fc\" ><span class=\"jet-download__icon jet-download-icon-left jet-elements-icon\"><i aria-hidden=\"true\" class=\"fas fa-file-download\"><\/i><\/span><span class=\"jet-download__text\"><span class=\"jet-download__label\">Descargar la ficha t\u00e9cnica<\/span><span class=\"jet-download__file-name\"><\/span><small class=\"jet-download__sub-label\"><\/small><\/span><\/a>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7798276a elementor-widget elementor-widget-menu-anchor\" data-id=\"7798276a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"ancla\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6b887939 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6b887939\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-24690f37\" data-id=\"24690f37\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d524c8e elementor-widget elementor-widget-jet-accordion\" data-id=\"2d524c8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"jet-accordion\" data-settings=\"{&quot;collapsible&quot;:false,&quot;ajaxTemplate&quot;:false,&quot;switchScrolling&quot;:false,&quot;switchScrollingOffset&quot;:0,&quot;switchScrollingDelay&quot;:500}\">\n\t\t\t<div class=\"jet-accordion__inner\">\n\t\t\t\t<div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-7601\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"1\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-7601\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-left\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><i class=\"fas fa-plus\"><\/i><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><i class=\"fas fa-minus\"><\/i><\/span><\/div><div class=\"jet-toggle__label-text\">Descripci\u00f3n<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-7601\" class=\"jet-toggle__content\" data-toggle=\"1\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><p>Esta es la tabla <strong>AGORA <\/strong> de <strong>SOPLAIR<\/strong>. Una mesa digna de su sal\u00f3n, \u00a1pero apta para el camping!<\/p>\n<p>Una encimera de bamb\u00fa de una sola pieza para mayor resistencia y patas multidireccionales ajustables en altura para adaptarse a suelos irregulares.<\/p>\n<p>Funda de transporte incluida.<\/p>\n<p>Disponible en tres tama\u00f1os: <strong>2<\/strong> personas, <strong>4<\/strong> personas y <strong>6<\/strong> personas.<\/p>\n<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-7602\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"2\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-7602\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-left\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><i class=\"fas fa-plus\"><\/i><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><i class=\"fas fa-minus\"><\/i><\/span><\/div><div class=\"jet-toggle__label-text\">Para m\u00e1s informaci\u00f3n<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-7602\" class=\"jet-toggle__content\" data-toggle=\"2\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><p>Bandeja: Bamb\u00fa<\/p>\n<p>Estructura : Aluminio<\/p>\n<p>Altura de las patas: de 52 a 70 cm<\/p>\n<p>Dimensiones abiertas (Largo x Fondo x Alto) : 100 x 68 x 70 cm<\/p>\n<p>Dimensiones plegado (Largo x Fondo x Alto) : 100 x 68 x 7cm<\/p>\n<p>Carga m\u00e1xima : 30 kg<\/p>\n<p>Peso: 9 kg<\/p>\n<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-7603\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"3\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-7603\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-left\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><i class=\"fas fa-plus\"><\/i><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><i class=\"fas fa-minus\"><\/i><\/span><\/div><div class=\"jet-toggle__label-text\">Accesorios adicionales<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-7603\" class=\"jet-toggle__content\" data-toggle=\"3\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Accueil MESA AGORA 2 PERSONAS Precio de venta recomendado : 149,90\u20ac Ref. : 697123 Esta es la mesa SOPLAIR AGORA. Una mesa digna de su sal\u00f3n, pero adecuada para acampar, ver m\u00e1s &#8230; PUNTOS CLAVE RESISTENTE F\u00c1CIL MANTENIMIENTO PLEGADO F\u00c1CIL PLEGADO ULTRARR\u00c1PIDO Descargar la ficha t\u00e9cnica Descripci\u00f3n Esta es la tabla AGORA de SOPLAIR. Una [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":12738,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-12740","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mesa Agora 2P - Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/soplair.com\/es\/productos\/mesas\/mesa-agora-2p\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mesa Agora 2P - Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...\" \/>\n<meta property=\"og:description\" content=\"Accueil MESA AGORA 2 PERSONAS Precio de venta recomendado : 149,90\u20ac Ref. : 697123 Esta es la mesa SOPLAIR AGORA. Una mesa digna de su sal\u00f3n, pero adecuada para acampar, ver m\u00e1s &#8230; PUNTOS CLAVE RESISTENTE F\u00c1CIL MANTENIMIENTO PLEGADO F\u00c1CIL PLEGADO ULTRARR\u00c1PIDO Descargar la ficha t\u00e9cnica Descripci\u00f3n Esta es la tabla AGORA de SOPLAIR. Una [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/soplair.com\/es\/productos\/mesas\/mesa-agora-2p\/\" \/>\n<meta property=\"og:site_name\" content=\"Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-08T08:59:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/soplair.com\/wp-content\/uploads\/elementor\/thumbs\/agora-2-1-1-qqo3e98phqdnib1loczakk4z2x586g00nfd6kb3pq8.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/soplair.com\/es\/productos\/mesas\/mesa-agora-2p\/\",\"url\":\"https:\/\/soplair.com\/es\/productos\/mesas\/mesa-agora-2p\/\",\"name\":\"Mesa Agora 2P - Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...\",\"isPartOf\":{\"@id\":\"https:\/\/soplair.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/soplair.com\/es\/productos\/mesas\/mesa-agora-2p\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/soplair.com\/es\/productos\/mesas\/mesa-agora-2p\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/soplair.com\/wp-content\/uploads\/elementor\/thumbs\/agora-2-1-1-qqo3e98phqdnib1loczakk4z2x586g00nfd6kb3pq8.png\",\"datePublished\":\"2024-04-29T14:24:44+00:00\",\"dateModified\":\"2024-07-08T08:59:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/soplair.com\/es\/productos\/mesas\/mesa-agora-2p\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/soplair.com\/es\/productos\/mesas\/mesa-agora-2p\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/soplair.com\/es\/productos\/mesas\/mesa-agora-2p\/#primaryimage\",\"url\":\"https:\/\/soplair.com\/wp-content\/uploads\/elementor\/thumbs\/agora-2-1-1-qqo3e98phqdnib1loczakk4z2x586g00nfd6kb3pq8.png\",\"contentUrl\":\"https:\/\/soplair.com\/wp-content\/uploads\/elementor\/thumbs\/agora-2-1-1-qqo3e98phqdnib1loczakk4z2x586g00nfd6kb3pq8.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/soplair.com\/es\/productos\/mesas\/mesa-agora-2p\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Productos\",\"item\":\"https:\/\/soplair.com\/es\/productos\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mesas\",\"item\":\"https:\/\/soplair.com\/es\/produits\/tables\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mesa Agora 2P\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/soplair.com\/es\/#website\",\"url\":\"https:\/\/soplair.com\/es\/\",\"name\":\"Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...\",\"description\":\"ISOLANTS THERMIQUES &amp; MOBILIERS DE PLEIN-AIR POUR VOS LOISIRS. Les produits SOPLAIR. AUVENTS TRADITIONNELS &amp; GONFLABLES SP\u00c9CIAL CARAVANES.\",\"publisher\":{\"@id\":\"https:\/\/soplair.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/soplair.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/soplair.com\/es\/#organization\",\"name\":\"Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...\",\"url\":\"https:\/\/soplair.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/soplair.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/soplair.com\/wp-content\/uploads\/2020\/01\/cropped-Fichier-1.png\",\"contentUrl\":\"https:\/\/soplair.com\/wp-content\/uploads\/2020\/01\/cropped-Fichier-1.png\",\"width\":1719,\"height\":507,\"caption\":\"Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...\"},\"image\":{\"@id\":\"https:\/\/soplair.com\/es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mesa Agora 2P - Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/soplair.com\/es\/productos\/mesas\/mesa-agora-2p\/","og_locale":"es_ES","og_type":"article","og_title":"Mesa Agora 2P - Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...","og_description":"Accueil MESA AGORA 2 PERSONAS Precio de venta recomendado : 149,90\u20ac Ref. : 697123 Esta es la mesa SOPLAIR AGORA. Una mesa digna de su sal\u00f3n, pero adecuada para acampar, ver m\u00e1s &#8230; PUNTOS CLAVE RESISTENTE F\u00c1CIL MANTENIMIENTO PLEGADO F\u00c1CIL PLEGADO ULTRARR\u00c1PIDO Descargar la ficha t\u00e9cnica Descripci\u00f3n Esta es la tabla AGORA de SOPLAIR. Una [&hellip;]","og_url":"https:\/\/soplair.com\/es\/productos\/mesas\/mesa-agora-2p\/","og_site_name":"Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...","article_modified_time":"2024-07-08T08:59:40+00:00","og_image":[{"url":"https:\/\/soplair.com\/wp-content\/uploads\/elementor\/thumbs\/agora-2-1-1-qqo3e98phqdnib1loczakk4z2x586g00nfd6kb3pq8.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/soplair.com\/es\/productos\/mesas\/mesa-agora-2p\/","url":"https:\/\/soplair.com\/es\/productos\/mesas\/mesa-agora-2p\/","name":"Mesa Agora 2P - Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...","isPartOf":{"@id":"https:\/\/soplair.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/soplair.com\/es\/productos\/mesas\/mesa-agora-2p\/#primaryimage"},"image":{"@id":"https:\/\/soplair.com\/es\/productos\/mesas\/mesa-agora-2p\/#primaryimage"},"thumbnailUrl":"https:\/\/soplair.com\/wp-content\/uploads\/elementor\/thumbs\/agora-2-1-1-qqo3e98phqdnib1loczakk4z2x586g00nfd6kb3pq8.png","datePublished":"2024-04-29T14:24:44+00:00","dateModified":"2024-07-08T08:59:40+00:00","breadcrumb":{"@id":"https:\/\/soplair.com\/es\/productos\/mesas\/mesa-agora-2p\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/soplair.com\/es\/productos\/mesas\/mesa-agora-2p\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/soplair.com\/es\/productos\/mesas\/mesa-agora-2p\/#primaryimage","url":"https:\/\/soplair.com\/wp-content\/uploads\/elementor\/thumbs\/agora-2-1-1-qqo3e98phqdnib1loczakk4z2x586g00nfd6kb3pq8.png","contentUrl":"https:\/\/soplair.com\/wp-content\/uploads\/elementor\/thumbs\/agora-2-1-1-qqo3e98phqdnib1loczakk4z2x586g00nfd6kb3pq8.png"},{"@type":"BreadcrumbList","@id":"https:\/\/soplair.com\/es\/productos\/mesas\/mesa-agora-2p\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Productos","item":"https:\/\/soplair.com\/es\/productos\/"},{"@type":"ListItem","position":2,"name":"Mesas","item":"https:\/\/soplair.com\/es\/produits\/tables\/"},{"@type":"ListItem","position":3,"name":"Mesa Agora 2P"}]},{"@type":"WebSite","@id":"https:\/\/soplair.com\/es\/#website","url":"https:\/\/soplair.com\/es\/","name":"Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...","description":"ISOLANTS THERMIQUES &amp; MOBILIERS DE PLEIN-AIR POUR VOS LOISIRS. Les produits SOPLAIR. AUVENTS TRADITIONNELS &amp; GONFLABLES SP\u00c9CIAL CARAVANES.","publisher":{"@id":"https:\/\/soplair.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/soplair.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/soplair.com\/es\/#organization","name":"Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...","url":"https:\/\/soplair.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/soplair.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/soplair.com\/wp-content\/uploads\/2020\/01\/cropped-Fichier-1.png","contentUrl":"https:\/\/soplair.com\/wp-content\/uploads\/2020\/01\/cropped-Fichier-1.png","width":1719,"height":507,"caption":"Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ..."},"image":{"@id":"https:\/\/soplair.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/soplair.com\/es\/wp-json\/wp\/v2\/pages\/12740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soplair.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/soplair.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/soplair.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/soplair.com\/es\/wp-json\/wp\/v2\/comments?post=12740"}],"version-history":[{"count":25,"href":"https:\/\/soplair.com\/es\/wp-json\/wp\/v2\/pages\/12740\/revisions"}],"predecessor-version":[{"id":16938,"href":"https:\/\/soplair.com\/es\/wp-json\/wp\/v2\/pages\/12740\/revisions\/16938"}],"up":[{"embeddable":true,"href":"https:\/\/soplair.com\/es\/wp-json\/wp\/v2\/pages\/12738"}],"wp:attachment":[{"href":"https:\/\/soplair.com\/es\/wp-json\/wp\/v2\/media?parent=12740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}