{"id":19349,"date":"2026-03-25T19:00:31","date_gmt":"2026-03-25T18:00:31","guid":{"rendered":"https:\/\/soplair.com\/?page_id=19349"},"modified":"2026-03-26T12:20:10","modified_gmt":"2026-03-26T11:20:10","slug":"tienda-de-techo-rigida-sunshine","status":"publish","type":"page","link":"https:\/\/soplair.com\/es\/productos\/tienda-de-techo\/tienda-de-techo-rigida-sunshine\/","title":{"rendered":"Tienda de techo r\u00edgida SUNSHINE"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"19349\" class=\"elementor elementor-19349 elementor-19301\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-17a0a95b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"17a0a95b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-40ee6076\" data-id=\"40ee6076\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d87bafe elementor-widget elementor-widget-jet-breadcrumbs\" data-id=\"3d87bafe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-jet-breadcrumbs jet-blocks\">\n\t\t<div class=\"jet-breadcrumbs\">\n\t\t<div class=\"jet-breadcrumbs__content\">\n\t\t<div class=\"jet-breadcrumbs__wrap\"><div class=\"jet-breadcrumbs__item\"><a href=\"https:\/\/soplair.com\/es\/\" class=\"jet-breadcrumbs__item-link is-home\" rel=\"home\" title=\"Inicio\">Inicio<\/a><\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3dade6a5 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"3dade6a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;autoplay_speed&quot;:3500,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrousel d\u2019images\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/soplair.com\/wp-content\/uploads\/2026\/03\/777580_S1-1-300x198.jpg\" alt=\"777580_S1 (1)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/soplair.com\/wp-content\/uploads\/2026\/03\/777580_PA-2-300x198.jpg\" alt=\"777580_PA (2)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/soplair.com\/wp-content\/uploads\/2026\/03\/777580_S2-300x200.jpg\" alt=\"default\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/soplair.com\/wp-content\/uploads\/2026\/03\/777580_S4-300x200.jpg\" alt=\"777580_S4\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/soplair.com\/wp-content\/uploads\/2026\/03\/777580_D2-300x200.jpg\" alt=\"777580_D2\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 de 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/soplair.com\/wp-content\/uploads\/2026\/03\/777580_D4-1-300x200.jpg\" alt=\"777580_D4 (1)\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d9f4d54 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4d9f4d54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d70cad6 elementor-widget elementor-widget-heading\" data-id=\"5d70cad6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tienda de techo r\u00edgida SUNSHINE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-695df855 elementor-widget elementor-widget-text-editor\" data-id=\"695df855\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5>Precio de venta recomendado: 1 990,00 \u20ac<\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58f5f4a0 elementor-widget elementor-widget-text-editor\" data-id=\"58f5f4a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><strong>Ref. : 777580<\/strong><\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2984a2e6 elementor-widget elementor-widget-text-editor\" data-id=\"2984a2e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5>Tienda de techo r\u00edgida Soplair Sunshine con carcasa de ABS + PC y lona de polialgod\u00f3n de 320 g\/m\u00b2, dise\u00f1ada para alojar a 2 adultos y 1 ni\u00f1o.<\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5490ed1 elementor-align-center e-transform elementor-widget elementor-widget-jet-download-button\" data-id=\"5490ed1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.1,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"jet-download-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-jet-download-button jet-elements\"><a class=\"elementor-button elementor-size-md jet-download jet-download-icon-position-left\" data-e-disable-page-transition=\"true\" href=\"https:\/\/soplair.com\/es\/?jet_download=d8cdceee2881a8a0fea3c167b8a38904959f08ac\" ><span class=\"jet-download__icon jet-download-icon-left jet-elements-icon\"><i aria-hidden=\"true\" class=\"fas fa-file-download\"><\/i><\/span><span class=\"jet-download__text\"><span class=\"jet-download__label\">Descargar la ficha t\u00e9cnica<\/span><span class=\"jet-download__file-name\"><\/span><small class=\"jet-download__sub-label\"><\/small><\/span><\/a>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6fd61d0d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6fd61d0d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4c0085be\" data-id=\"4c0085be\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fc8cced elementor-widget elementor-widget-menu-anchor\" data-id=\"fc8cced\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"ancre\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24b231bb elementor-widget elementor-widget-jet-accordion\" data-id=\"24b231bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"jet-accordion\" data-settings=\"{&quot;collapsible&quot;:false,&quot;ajaxTemplate&quot;:false,&quot;switchScrolling&quot;:false,&quot;switchScrollingOffset&quot;:0,&quot;switchScrollingDelay&quot;:500}\">\n\t\t\t<div class=\"jet-accordion__inner\">\n\t\t\t\t<div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-6151\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"1\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-6151\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-left\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><i class=\"fas fa-plus\"><\/i><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><i class=\"fas fa-minus\"><\/i><\/span><\/div><div class=\"jet-toggle__label-text\">Descripci\u00f3n<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-6151\" class=\"jet-toggle__content\" data-toggle=\"1\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><h2>Tienda de techo r\u00edgida Sunshine \u2013 Soplair<\/h2>\n<p>La tienda de techo r\u00edgida Sunshine de Soplair est\u00e1 dise\u00f1ada para instalarse en el techo de un veh\u00edculo. Combina una estructura r\u00edgida y una lona de polialgod\u00f3n para ofrecer un espacio elevado para dormir destinado a varios ocupantes. <\/p>\n<h3>Estructura y dise\u00f1o<\/h3>\n<p>La tienda est\u00e1 equipada con una carcasa r\u00edgida fabricada en ABS + PC. La parte inferior de la carcasa es de ABS con un acabado brillante. La lona es de policoton con un gramaje de 320 g\/m\u00b2 y un revestimiento de PU de 3000 mm. Incorpora una protecci\u00f3n contra la lluvia de poli\u00e9ster de 160 g\/m\u00b2 con un revestimiento de PU de 10 000 mm.<br \/>El conjunto se compone de una lona gris y una carcasa negra.   <\/p>\n<h3>Dormitorio y distribuci\u00f3n interior<\/h3>\n<p>La superficie para dormir tiene unas dimensiones de 143 x 220 cm. La capacidad es para 2 adultos y 1 ni\u00f1o.<br \/>La tienda incluye un colch\u00f3n de espuma con funda extra\u00edble. En el interior hay dos bolsillos para guardar objetos y ganchos para colgar una l\u00e1mpara de camping. Se incluye una l\u00e1mpara.   <\/p>\n<h3>Aberturas, ventilaci\u00f3n y equipamiento<\/h3>\n<p>La tienda dispone de un sistema de apertura semiautom\u00e1tico con cuatro pistones de gas, protegidos por una tela.<br \/>Las aberturas incluyen dos puertas y varias ventanas equipadas con contraventanas y mosquiteras. Una mosquitera exterior rodea la tienda, lo que contribuye a la ventilaci\u00f3n.<br \/>Cada lado largo cuenta con un toldo negro, muescas para barras met\u00e1licas y un ojal met\u00e1lico. Unos cierres permiten mantener las aberturas en posici\u00f3n abierta. Una escalera de aluminio de 2,3 m con bolsa de transporte.  <\/p>\n<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-6152\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"2\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-6152\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-left\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><i class=\"fas fa-plus\"><\/i><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><i class=\"fas fa-minus\"><\/i><\/span><\/div><div class=\"jet-toggle__label-text\">Para m\u00e1s informaci\u00f3n<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-6152\" class=\"jet-toggle__content\" data-toggle=\"2\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><ul>\n<li>Marca: Soplair<\/li>\n<li>Modelo: Sunshine<\/li>\n<li>Color: Lona gris \/ Carcasa negra<\/li>\n<li>Otras caracter\u00edsticas:\n<ul>\n<li>Lona de polialgod\u00f3n 320 g\/m\u00b2<\/li>\n<li>Carcasa r\u00edgida de ABS + PC<\/li>\n<li>Apertura semiautom\u00e1tica con 4 cilindros de gas<\/li>\n<li>Dimensiones de la superficie de descanso: 143 x 220 cm<\/li>\n<li>Capacidad: 2 adultos + 1 ni\u00f1o<\/li>\n<li>Grosor del colch\u00f3n: aproximadamente 7,5 cm<\/li>\n<li>Longitud: 2,3 m<\/li>\n<li>Ancho: 152 cm<\/li>\n<li>Altura cerrado: 27,2 cm<\/li>\n<li>Altura abierta: 99,5 cm<\/li>\n<li>Peso neto: 81,5 kg<\/li>\n<li>Escalera de aluminio de 2,3 m con bolsa de transporte.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-6153\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"3\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-6153\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-left\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><i class=\"fas fa-plus\"><\/i><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><i class=\"fas fa-minus\"><\/i><\/span><\/div><div class=\"jet-toggle__label-text\">Accesorios adicionales<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-6153\" class=\"jet-toggle__content\" data-toggle=\"3\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Accueil Tienda de techo r\u00edgida SUNSHINE Precio de venta recomendado: 1 990,00 \u20ac Ref. : 777580 Tienda de techo r\u00edgida Soplair Sunshine con carcasa de ABS + PC y lona de polialgod\u00f3n de 320 g\/m\u00b2, dise\u00f1ada para alojar a 2 adultos y 1 ni\u00f1o. Descargar la ficha t\u00e9cnica Descripci\u00f3n Tienda de techo r\u00edgida Sunshine \u2013 [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":19517,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-19349","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tienda de techo r\u00edgida SUNSHINE - Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/soplair.com\/es\/productos\/tienda-de-techo\/tienda-de-techo-rigida-sunshine\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tienda de techo r\u00edgida SUNSHINE - Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...\" \/>\n<meta property=\"og:description\" content=\"Accueil Tienda de techo r\u00edgida SUNSHINE Precio de venta recomendado: 1 990,00 \u20ac Ref. : 777580 Tienda de techo r\u00edgida Soplair Sunshine con carcasa de ABS + PC y lona de polialgod\u00f3n de 320 g\/m\u00b2, dise\u00f1ada para alojar a 2 adultos y 1 ni\u00f1o. Descargar la ficha t\u00e9cnica Descripci\u00f3n Tienda de techo r\u00edgida Sunshine \u2013 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/soplair.com\/es\/productos\/tienda-de-techo\/tienda-de-techo-rigida-sunshine\/\" \/>\n<meta property=\"og:site_name\" content=\"Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-26T11:20:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/soplair.com\/wp-content\/uploads\/2026\/03\/777580_S1-1-300x198.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/soplair.com\/es\/productos\/tienda-de-techo\/tienda-de-techo-rigida-sunshine\/\",\"url\":\"https:\/\/soplair.com\/es\/productos\/tienda-de-techo\/tienda-de-techo-rigida-sunshine\/\",\"name\":\"Tienda de techo r\u00edgida SUNSHINE - Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...\",\"isPartOf\":{\"@id\":\"https:\/\/soplair.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/soplair.com\/es\/productos\/tienda-de-techo\/tienda-de-techo-rigida-sunshine\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/soplair.com\/es\/productos\/tienda-de-techo\/tienda-de-techo-rigida-sunshine\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/soplair.com\/wp-content\/uploads\/2026\/03\/777580_S1-1-300x198.jpg\",\"datePublished\":\"2026-03-25T18:00:31+00:00\",\"dateModified\":\"2026-03-26T11:20:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/soplair.com\/es\/productos\/tienda-de-techo\/tienda-de-techo-rigida-sunshine\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/soplair.com\/es\/productos\/tienda-de-techo\/tienda-de-techo-rigida-sunshine\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/soplair.com\/es\/productos\/tienda-de-techo\/tienda-de-techo-rigida-sunshine\/#primaryimage\",\"url\":\"https:\/\/soplair.com\/wp-content\/uploads\/2026\/03\/777580_S1-1-300x198.jpg\",\"contentUrl\":\"https:\/\/soplair.com\/wp-content\/uploads\/2026\/03\/777580_S1-1-300x198.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/soplair.com\/es\/productos\/tienda-de-techo\/tienda-de-techo-rigida-sunshine\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Productos\",\"item\":\"https:\/\/soplair.com\/es\/productos\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda de techo\",\"item\":\"https:\/\/soplair.com\/es\/productos\/tienda-de-techo\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tienda de techo r\u00edgida SUNSHINE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/soplair.com\/es\/#website\",\"url\":\"https:\/\/soplair.com\/es\/\",\"name\":\"Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...\",\"description\":\"ISOLANTS THERMIQUES &amp; MOBILIERS DE PLEIN-AIR POUR VOS LOISIRS. Les produits SOPLAIR. AUVENTS TRADITIONNELS &amp; GONFLABLES SP\u00c9CIAL CARAVANES.\",\"publisher\":{\"@id\":\"https:\/\/soplair.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/soplair.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/soplair.com\/es\/#organization\",\"name\":\"Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...\",\"url\":\"https:\/\/soplair.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/soplair.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/soplair.com\/wp-content\/uploads\/2020\/01\/cropped-Fichier-1.png\",\"contentUrl\":\"https:\/\/soplair.com\/wp-content\/uploads\/2020\/01\/cropped-Fichier-1.png\",\"width\":1719,\"height\":507,\"caption\":\"Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...\"},\"image\":{\"@id\":\"https:\/\/soplair.com\/es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tienda de techo r\u00edgida SUNSHINE - Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/soplair.com\/es\/productos\/tienda-de-techo\/tienda-de-techo-rigida-sunshine\/","og_locale":"es_ES","og_type":"article","og_title":"Tienda de techo r\u00edgida SUNSHINE - Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...","og_description":"Accueil Tienda de techo r\u00edgida SUNSHINE Precio de venta recomendado: 1 990,00 \u20ac Ref. : 777580 Tienda de techo r\u00edgida Soplair Sunshine con carcasa de ABS + PC y lona de polialgod\u00f3n de 320 g\/m\u00b2, dise\u00f1ada para alojar a 2 adultos y 1 ni\u00f1o. Descargar la ficha t\u00e9cnica Descripci\u00f3n Tienda de techo r\u00edgida Sunshine \u2013 [&hellip;]","og_url":"https:\/\/soplair.com\/es\/productos\/tienda-de-techo\/tienda-de-techo-rigida-sunshine\/","og_site_name":"Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...","article_modified_time":"2026-03-26T11:20:10+00:00","og_image":[{"url":"https:\/\/soplair.com\/wp-content\/uploads\/2026\/03\/777580_S1-1-300x198.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/soplair.com\/es\/productos\/tienda-de-techo\/tienda-de-techo-rigida-sunshine\/","url":"https:\/\/soplair.com\/es\/productos\/tienda-de-techo\/tienda-de-techo-rigida-sunshine\/","name":"Tienda de techo r\u00edgida SUNSHINE - Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...","isPartOf":{"@id":"https:\/\/soplair.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/soplair.com\/es\/productos\/tienda-de-techo\/tienda-de-techo-rigida-sunshine\/#primaryimage"},"image":{"@id":"https:\/\/soplair.com\/es\/productos\/tienda-de-techo\/tienda-de-techo-rigida-sunshine\/#primaryimage"},"thumbnailUrl":"https:\/\/soplair.com\/wp-content\/uploads\/2026\/03\/777580_S1-1-300x198.jpg","datePublished":"2026-03-25T18:00:31+00:00","dateModified":"2026-03-26T11:20:10+00:00","breadcrumb":{"@id":"https:\/\/soplair.com\/es\/productos\/tienda-de-techo\/tienda-de-techo-rigida-sunshine\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/soplair.com\/es\/productos\/tienda-de-techo\/tienda-de-techo-rigida-sunshine\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/soplair.com\/es\/productos\/tienda-de-techo\/tienda-de-techo-rigida-sunshine\/#primaryimage","url":"https:\/\/soplair.com\/wp-content\/uploads\/2026\/03\/777580_S1-1-300x198.jpg","contentUrl":"https:\/\/soplair.com\/wp-content\/uploads\/2026\/03\/777580_S1-1-300x198.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/soplair.com\/es\/productos\/tienda-de-techo\/tienda-de-techo-rigida-sunshine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Productos","item":"https:\/\/soplair.com\/es\/productos\/"},{"@type":"ListItem","position":2,"name":"Tienda de techo","item":"https:\/\/soplair.com\/es\/productos\/tienda-de-techo\/"},{"@type":"ListItem","position":3,"name":"Tienda de techo r\u00edgida SUNSHINE"}]},{"@type":"WebSite","@id":"https:\/\/soplair.com\/es\/#website","url":"https:\/\/soplair.com\/es\/","name":"Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...","description":"ISOLANTS THERMIQUES &amp; MOBILIERS DE PLEIN-AIR POUR VOS LOISIRS. Les produits SOPLAIR. AUVENTS TRADITIONNELS &amp; GONFLABLES SP\u00c9CIAL CARAVANES.","publisher":{"@id":"https:\/\/soplair.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/soplair.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/soplair.com\/es\/#organization","name":"Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ...","url":"https:\/\/soplair.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/soplair.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/soplair.com\/wp-content\/uploads\/2020\/01\/cropped-Fichier-1.png","contentUrl":"https:\/\/soplair.com\/wp-content\/uploads\/2020\/01\/cropped-Fichier-1.png","width":1719,"height":507,"caption":"Page d&#039;accueil | Soplair\u2122 Fabricant d&#039;accessoires de Loisirs ..."},"image":{"@id":"https:\/\/soplair.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/soplair.com\/es\/wp-json\/wp\/v2\/pages\/19349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soplair.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/soplair.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/soplair.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/soplair.com\/es\/wp-json\/wp\/v2\/comments?post=19349"}],"version-history":[{"count":2,"href":"https:\/\/soplair.com\/es\/wp-json\/wp\/v2\/pages\/19349\/revisions"}],"predecessor-version":[{"id":19518,"href":"https:\/\/soplair.com\/es\/wp-json\/wp\/v2\/pages\/19349\/revisions\/19518"}],"up":[{"embeddable":true,"href":"https:\/\/soplair.com\/es\/wp-json\/wp\/v2\/pages\/19517"}],"wp:attachment":[{"href":"https:\/\/soplair.com\/es\/wp-json\/wp\/v2\/media?parent=19349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}